{"id":768,"date":"2016-10-17T15:18:11","date_gmt":"2016-10-17T13:18:11","guid":{"rendered":"https:\/\/letiziainnocenti.it\/privacy-policy\/"},"modified":"2016-10-17T15:18:11","modified_gmt":"2016-10-17T13:18:11","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/","title":{"rendered":"Privacy policy"},"content":{"rendered":"<p>PRIVACY<br \/>\nPrivacy Policy \u2013 Informativa in materia di protezione dei dati personali<br \/>\n(13 del GDPR 2016\/679)<br \/>\nIn questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano.<br \/>\nSi tratta di una informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del GDPR 2016\/679 \u2013 GDPR a coloro che interagiscono con i servizi web del presente sito per la protezione dei dati personali, accessibili per via telematica a partire dall\u2019indirizzo: WWW corrispondente alla pagina iniziale del sito.<br \/>\nL\u2019informativa \u00e8 resa solo per il presente sito e non anche per altri siti web collegati tramite link a questo sito che l\u2019utente pu\u00f2 eventualmente consultare. I siti web esterni collegati potrebbero avere una politica della privacy diversa da quella riportata nel presente sito.<\/p>\n<p>IL \u201cTITOLARE\u201d DEL TRATTAMENTO<\/p>\n<p>A seguito della consultazione di questo sito possono essere trattati dati relativi a persone identificate o identificabili.<br \/>\nIl \u201cTITOLARE\u201d del loro trattamento \u00e8 TITOLARE<br \/>\nLUOGO DI TRATTAMENTO DEI DATI<\/p>\n<p>I trattamenti connessi ai servizi web di questo sito hanno luogo presso la predetta sede del TITOLARE e sono curati solo da personale tecnico incaricato del trattamento, oppure da eventuali incaricati di occasionali operazioni di manutenzione.<br \/>\nNessun dato derivante dal servizio web viene comunicato o diffuso.<br \/>\nI dati personali forniti dagli utenti che inoltrano richieste di iscrizione sito sono utilizzati al solo fine di eseguire il servizio o la prestazione richiesta e sono comunicati a terzi nel solo caso in cui ci\u00f2 sia a tal fine necessario.<br \/>\nTIPI DI DATI TRATTATI<\/p>\n<p>Dati di navigazione<br \/>\nI sistemi informatici e le procedure software preposte al funzionamento di questo sito web acquisiscono, nel corso del loro normale esercizio, alcuni dati personali la cui trasmissione \u00e8 implicita nell\u2019uso dei protocolli di comunicazione di Internet.<br \/>\nSi tratta di informazioni che non sono raccolte per essere associate a interessati identificati, ma che per loro stessa natura potrebbero, attraverso elaborazioni ed associazioni con dati detenuti da terzi, permettere di identificare gli utenti.<br \/>\nIn questa categoria di dati rientrano gli indirizzi IP o i nomi a dominio dei computer utilizzati dagli utenti che si connettono al sito, gli indirizzi in notazione URI (Uniform Resource Identifier) delle risorse richieste, l\u2019orario della richiesta, il metodo utilizzato nel sottoporre la richiesta al server, la dimensione del file ottenuto in risposta, il codice numerico indicante lo stato della risposta data dal server (buon fine, errore, ecc.) ed altri parametri relativi al sistema operativo e all\u2019ambiente informatico dell\u2019utente.<br \/>\nQuesti dati vengono utilizzati al solo fine di ricavare informazioni statistiche anonime sull\u2019uso del sito e per controllarne il corretto funzionamento e vengono cancellati immediatamente dopo l\u2019elaborazione. I dati potrebbero essere utilizzati per l\u2019accertamento di responsabilit\u00e0 in caso di ipotetici reati informatici ai danni del sito: salva questa eventualit\u00e0, allo stato i dati sui contatti web non persistono per pi\u00f9 di sette giorni.<br \/>\nDati forniti volontariamente dall\u2019utente<br \/>\nL\u2019invio facoltativo, esplicito e volontario di posta elettronica agli indirizzi indicati su questo sito comporta la successiva acquisizione dell\u2019indirizzo del mittente, necessario per rispondere alle richieste, nonch\u00e9 degli eventuali altri dati personali inseriti nella missiva.<br \/>\nSpecifiche informative di sintesi verranno progressivamente riportate o visualizzate nelle pagine del sito predisposte per particolari servizi a richiesta.<br \/>\nL\u2019utilizzo del sito pu\u00f2 richiedere altres\u00ec la comunicazione di qualunque informazione relativa a persona fisica, persona giuridica, ente od associazione, identificati o identificabili, anche indirettamente mediante riferimento a qualsiasi altra informazione, ivi compreso un numero di identificazione personale, quale in via esemplificativa ma non esaustiva nome, sesso, indirizzo, numero telefonico, indirizzo email, dati bancari ed ogni altra informazione che permetta l\u2019identificazione dell\u2019utente in qualsiasi momento attraverso l\u2019utilizzo del sito web.<br \/>\nSi tratta in ogni caso di dati personali necessari per l\u2019utilizzo del servizio.<br \/>\nTITOLARE pu\u00f2 venire a conoscenza di tali dati mediante l\u2019inserimento delle informazioni relative all\u2019account personale dell\u2019utente al fine della registrazione ed iscrizione al sito.<br \/>\nFACOLTATIVITA\u2019 DEL CONFERIMENTO DEI DATI<\/p>\n<p>A parte quanto specificato per i dati di navigazione, l\u2019utente \u00e8 libero di fornire i dati personali riportati nei moduli di accettazione\/iscrizione al sito al TITOLARE o comunque indicati nella pagina di contatto di questo sito per sollecitare la prestazione dei servizi richiesti.<br \/>\nIl loro mancato conferimento pu\u00f2 comportare l\u2019impossibilit\u00e0 di ottenere quanto richiesto.<br \/>\nMODALITA\u2019 DEL TRATTAMENTO<\/p>\n<p>I dati personali sono trattati con strumenti automatizzati per il tempo strettamente necessario a conseguire gli scopi per cui sono stati raccolti.<br \/>\nSpecifiche misure di sicurezza sono osservate per prevenire la perdita dei dati, usi illeciti o non corretti ed accessi non autorizzati.<br \/>\nFINALITA\u2019 DEL TRATTAMENTO<\/p>\n<p>I dati conferiti volontariamente dall\u2019utente potranno essere trattati esclusivamente per le seguenti finalit\u00e0:<br \/>\n\u2013 registrazione, attivazione e mantenimento account;<br \/>\n\u2013 i dati resi anonimi sono utilizzati, anche in forma aggregata al fine di elaborare studi e statistiche.<br \/>\nI dati personali verranno trattati mediante strumenti elettronici e manuali, con modalit\u00e0 compatibili alle finalit\u00e0 dello stesso, tali da garantire la riservatezza, la sicurezza e l\u2019integrit\u00e0 dei dati.<br \/>\nCOMUNICAZIONE DEI DATI A TERZI<\/p>\n<p>TITOLARE si riserva la facolt\u00e0 di comunicare i dati personali conferiti dallo utente a:<br \/>\n\u2013 forze dell\u2019ordine, pubbliche autorit\u00e0 o consulenti legali in relazione a presunti reati o violazioni delle condizioni di utilizzo, ovvero nei casi previsti dalla legge.<br \/>\nDIRITTI DEGLI INTERESSATI<br \/>\nL\u2019interessato ha il diritto di ottenere dal TITOLARE del trattamento la rettifica dei dati personali inesatti o l\u2019integrazione dei dati incompleti che lo riguardano, l\u2019accesso ai propri dati personali, la cancellazione, la limitazione del trattamento, diritto di opposizione, diritto alla portabilit\u00e0 dei dati e diritto di revoca del consenso prestato.<br \/>\nLe richieste vanno rivolte a TITOLARE.<br \/>\nCOOKIES<br \/>\nCOSA SONO I COOKIE?<br \/>\nI cookie sono piccoli file di testo inviati dal sito al terminale dell\u2019interessato (solitamente al browser), dove vengono memorizzati per essere poi ritrasmessi al sito alla successiva visita del medesimo utente. Un cookie non pu\u00f2 richiamare nessun altro dato dal disco fisso dell\u2019utente n\u00e9 trasmettere virus informatici o acquisire indirizzi email. Ogni cookie \u00e8 unico per il web browser dell\u2019utente. Alcune delle funzioni dei cookie possono essere demandate ad altre tecnologie. Nel presente documento con il termine \u2018cookie\u2019 si vuol far riferimento sia ai cookie, propriamente detti, sia a tutte le tecnologie similari.<br \/>\nMediante i cookie \u00e8 possibile registrare informazioni relative alle sue preferenze, come le pagine navigate o il download di file dal ns. sito o altre azioni similari effettuate navigando il nostro sito.<\/p>\n<p>Utilizzo dei cookies<\/p>\n<p>Al fine di rendere i propri servizi il pi\u00f9 possibile efficienti e semplici da utilizzare questo Sito fa uso di cookies. Pertanto, quando si visita il Sito, viene inserita una quantit\u00e0 minima di informazioni nel dispositivo dell\u2019Utente, come piccoli file di testo chiamati \u201ccookie\u201d, che vengono salvati nella directory del browser Web dell\u2019Utente. Esistono diversi tipi di cookie, ma sostanzialmente lo scopo principale di un cookie \u00e8 quello di far funzionare pi\u00f9 efficacemente il Sito e di abilitarne determinate funzionalit\u00e0.<\/p>\n<p>I cookie sono utilizzati per migliorare la navigazione globale dell\u2019Utente. In particolare:<\/p>\n<p>Consentono di navigare in modo efficiente da una pagina all\u2019altra del sito Web.<br \/>\nMemorizzano il nome utente e le preferenze inserite.<br \/>\nConsentono di evitare di inserire le stesse informazioni (come nome utente e password) pi\u00f9 volte durante la visita.<br \/>\nMisurano l\u2019utilizzo dei servizi da parte degli Utenti, per ottimizzare l\u2019esperienza di navigazione e i servizi stessi.<br \/>\nPresentano informazioni pubblicitarie mirate in funzione degli interessi e del comportamento manifestato dall\u2019Utente durante la navigazione.<\/p>\n<p>Esistono vari tipi di cookie. Qui di seguito sono riportati i tipi cookie che possono essere utilizzati nel Sito con una descrizione della finalit\u00e0 legata all\u2019uso.<br \/>\nCookie tecnici<br \/>\nI cookie di questo tipo sono necessari per il corretto funzionamento di alcune aree del sito. I cookie di questa categoria comprendono sia cookie persistenti che cookie di sessione. In assenza di tali cookie, il sito o alcune porzioni di esso potrebbero non funzionare correttamente. Pertanto, vengono sempre utilizzati, indipendentemente dalle preferenze dall\u2019utente. I cookie di questa categoria vengono sempre inviati dal nostro dominio.<br \/>\nCookie analitici<br \/>\nI cookie di questo tipo vengono utilizzati per raccogliere informazioni sull\u2019utilizzo del sito. Il TITOLARE usa tali informazioni per analisi statistiche, per migliorare il sito e semplificarne l\u2019utilizzo, oltre che per monitorarne il corretto funzionamento. Questo tipo di cookie raccoglie informazioni in forma anonima sull\u2019attivit\u00e0 degli utenti nel sito e sul modo in cui sono arrivati al Sito e alle pagine visitate. I cookie di questa categoria vengono inviati dal Sito stesso o da domini di terze parti.<br \/>\nCookie di rilevamento di terze parti<br \/>\nI cookie di questo tipo vengono utilizzati per raccogliere informazioni sull\u2019utilizzo del sito Web da parte dei visitatori, le parole chiave usate per raggiungere il sito, i siti Web visitati e le origini del traffico da cui provengono i visitatori per le campagne di marketing. Il TITOLARE pu\u00f2 utilizzare tali informazioni per compilare rapporti e migliorare il Sito. I cookie raccolgono informazioni in forma anonima. I cookie di questo tipo vengono inviati dal Sito stesso o da domini di terze parti.<br \/>\nCookie per l\u2019integrazione di funzionalit\u00e0 di terze parti<br \/>\nI cookie di questo tipo vengono utilizzati per integrare funzionalit\u00e0 di terze parti nel Sito (ad esempio, moduli per i commenti o icone di social network che consentono ai visitatori di condividere il contenuto del sito). I cookie di questa categoria possono essere inviati dai domini dei siti partner o che comunque offrono le funzionalit\u00e0 presenti nel sito.<\/p>\n<p>Il TITOLARE non \u00e8 tenuto a richiedere il consenso dell\u2019utente per i cookie tecnici, poich\u00e9 questi sono strettamente necessari per la fornitura del servizio.<br \/>\nPer le altre tipologie di cookie il consenso pu\u00f2 essere espresso dall\u2019Utente, conformemente alla normativa vigente, mediante specifiche configurazioni del browser e di programmi informatici o di dispositivi che siano di facile e chiara utilizzabilit\u00e0 per l\u2019Utente. Il TITOLARE ricorda all\u2019Utente che \u00e8 possibile modificare le preferenze relative ai cookie in qualsiasi momento. \u00c8 anche possibile disabilitare in qualsiasi momento i cookie dal browser , ma questa operazione potrebbe impedire all\u2019Utente di utilizzare alcune parti del Sito.<br \/>\nSiti Web di terze parti<\/p>\n<p>Il sito contiene collegamenti ad altri siti Web che dispongono di una propria informativa sulla privacy. Queste informative sulla privacy possono essere diverse da quella adottata dal TITOLARE, che quindi non risponde per Siti di terze parti.<\/p>\n<p>Il consenso all\u2019utilizzo di tali cookie \u00e8 espresso dall\u2019interessato mediante il settaggio individuale che ha scelto liberamente per il browser utilizzato per la navigazione nel sito, ferma restando la facolt\u00e0 dell\u2019utente di comunicare in ogni momento al TITOLARE del trattamento la propria volont\u00e0 in merito ad dati gestiti per il tramite dei cookie che il browser stesso abbia accettato.<br \/>\nCOOKIE INSTALLATI SU QUESTO SITO<br \/>\nEcco l\u2019elenco dei cookie (raggruppati logicamente a livello di funzionalit\u00e0 o fornitore) presenti sul sito. I cookie di terze parti presentano il collegamento all\u2019informativa della privacy del relativo fornitore esterno, dove \u00e8 possibile trovare una dettagliata descrizione dei singoli cookie e del trattamento che ne viene fatto.<br \/>\nGoogle Analytics<br \/>\nSi tratta di cookie di monitoraggio per la generazione di statistiche sull\u2019utilizzo del sito. Google Analytics utilizza, nel nostro sito, cookie che non memorizzano dati personali e che vengono depositati sul computer dell\u2019utente per consentire al gestore del sito web di analizzare come gli utenti utilizzano il sito stesso. Abbiamo adottato strumenti che riducono il potere identificativo dei cookie tramite il mascheramento di porzioni significative dell\u2019IP. Per impedire la memorizzazione dei predetti cookie l\u2019utente potr\u00e0 scaricare l\u2019apposito componente aggiuntivo reperibile al seguente link: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\">https:\/\/tools.google.com\/dlpage\/gaoptout<\/a><\/p>\n<p>Google Adwords\/Adsense<br \/>\nE\u2019 un servizio fornito da Google Inc. E\u2019 la piattaforma pubblicitaria di Google che permette la pubblicazione di annunci testuali, immagini e video sulle pagine dei risultati di ricerca e sui siti della rete di contenuti Google. Il nostro sito utilizza Google Adwords unicamente per promuovere i propri servizi sul web. Inoltre utilizza servizi di remarketing che consentono di mostrare annunci pubblicitari agli utenti che hanno gi\u00e0 visitato questo sito web, mentre navigano in internet. Per maggiori informazioni consultare la pagina <a href=\"https:\/\/support.google.com\/adwords\/answer\/2407785?hl=it\">https:\/\/support.google.com\/adwords\/answer\/2407785?hl=it<\/a><\/p>\n<p>Google+ Platform<br \/>\nGoogle+ Platform utilizza cookie per offrire all\u2019utente funzionalit\u00e0 di condivisione sulla propria bacheca. Per maggiori informazioni, consultare la pagina <a href=\"https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/\">https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/<\/a><\/p>\n<p>Google Tag Manager<br \/>\nGoogle Tag Manager consente di implementare Google Analytics utilizzando il tag di Universal Analytics o la versione classica del tag.<br \/>\nPer maggiori informazioni, consultare la pagina <a href=\"https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/\">https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/<\/a><\/p>\n<p>Google AJAX Search API<br \/>\nGoogle AJAX Serarch API \u00e8 una libreria Javascript che permette di inserire la barra di ricerca di Google nelle pagine internet o in altri applicativi online.<br \/>\nPer maggiori informazioni, consultare la pagina <a href=\"https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/\">https:\/\/www.google.it\/intl\/it\/policies\/technologies\/cookies\/<\/a><\/p>\n<p>SALESmanago<br \/>\nIl codice di SALESmanago assegna diverse tipologie di cookie, che hanno prevalentemente lo scopo di:<br \/>\n\u2013 Monitorare le visite anonime e B2B (si tratta di cookies assegnati a tutti gli utenti che visitano il sito e accettano i cookies)<br \/>\n\u2013 Monitorare un contatto -specifico e identificato- per tracciarne il comportamento e le abitudini (si tratta di cookies assegnati al contatto nel caso in cui l\u2019utente effettui determinate azioni, come ad esempio, il click su un link inserito in un\u2019email SALESmanago o la compilazione di un form generato dal sistema o integrato via API)<br \/>\nPer ulteriori informazioni su tutte le tipologie di cookie assegnate dal sistema e sulle loro funzionalit\u00e0 \u00e8 possibile consultare la pagina dedicata.<\/p>\n<p>Gravatar<br \/>\nGravatar utilizza cookie per offrire all\u2019utente funzionalit\u00e0 di creazione di un avatar.<br \/>\nPer maggiori informazioni, consultare la pagina <a href=\"http:\/\/automattic.com\/privacy\/\">http:\/\/automattic.com\/privacy\/<\/a><\/p>\n<p>Smartlook<br \/>\nUtilizziamo i cookies di Smartlook per raccogliere informazioni necessarie alla comprensione dei comportamenti di navigazione dell\u2019utente, online. Il rilascio dei cookies pu\u00f2 essere impedito navigando in modalit\u00e0 \u201cin incognito\u201d, da qualsiasi browser. INFO: https:\/\/www.smartlook.com\/it\/privacy<\/p>\n<p>Pinterest<br \/>\nPinterest utilizza cookie per offrire all\u2019utente funzionalit\u00e0 di condivisione sulla propria bacheca. Per maggiori informazioni, consultare la pagina <a href=\"https:\/\/about.pinterest.com\/it\/privacy-policy\">https:\/\/about.pinterest.com\/it\/privacy-policy<\/a><\/p>\n<p>Twitter<br \/>\nTwitter utilizza cookie per offrire all\u2019utente funzionalit\u00e0 di condivisione sulla propria bacheca. Per maggiori informazioni, consultare la pagina<a href=\"https:\/\/support.twitter.com\/articles\/20170519-uso-dei-cookie-e-di-altre-tecnologie-simili-da-parte-di-twitter\"> https:\/\/support.twitter.com\/articles\/20170519-uso-dei-cookie-e-di-altre-tecnologie-simili-da-parte-di-twitter<\/a><\/p>\n<p>Facebook<br \/>\nFacebook utilizza cookie per offrire all\u2019utente funzionalit\u00e0 di condivisione e di \u201clike\u201d sulla propria bacheca. Per maggiori informazioni, consultare la pagina https:\/\/www.facebook.com\/about\/privacy<\/p>\n<p>Sono presenti cookie di profilazione sul nostro sito.<\/p>\n<p>DURATA DEI COOKIE<br \/>\nI cookie hanno una durata dettata dalla data di scadenza (o da un\u2019azione specifica come la chiusura del browser) impostata al momento dell\u2019installazione. I cookie possono essere:<br \/>\ntemporanei o di sessione (session cookie): sono utilizzati per archiviare informazioni temporanee, consentono di collegare le azioni eseguite durante una sessione specifica e vengono rimossi dal computer alla chiusura del browser;<br \/>\npermanenti (persistent cookie): sono utilizzati per archiviare informazioni, ad esempio il nome e la password di accesso, in modo da evitare che l\u2019utente debba digitarli nuovamente ogni volta che visita un sito specifico. Questi rimangono memorizzati nel computer anche dopo aver chiuso il browser.<br \/>\nI c.d. cookies di sessione, una volta terminata la connessione al presente sito web, non vengono conservati. I sistemi informatici utilizzati per il presente sito utilizzano sia cookie temporanei sia cookie permanenti.<\/p>\n<p>GESTIONE DEI COOKIE<br \/>\nPuoi disattivare i cookies presenti sui siti web scaricando appositi software quali Ghostery per il tuo browser e disabilitando l\u2019utilizzo dei singoli cookies. Oppure puoi attivare la modalit\u00e0 di \u201cnavigazione anonima\u201d \u2013 si tratta di una funzione che consente di navigare senza lasciare traccia nel browser dei dati di navigazione. Tale funzione consente unicamente di non mantenere i dati di navigazione nel browser.<br \/>\nIn alternativa, puoi disabilitare\/cancellare i cookie mediante l\u2019accesso al pannello di configurazione del tuo browser.<br \/>\nRiportiamo di seguito il link ai pannelli di configurazione di alcuni browser noti:<br \/>\nChrome<br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nMozilla Firefox<br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nInternet Explorer <br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nMicrosoft Edge<br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nSafari 6<br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nSafari iOS (dispositivi mobile)<br \/>\nPer maggiori informazioni visita la pagina dedicata.<br \/>\nOpera<br \/>\nPer maggiori informazioni visita la pagina dedicata.<\/p>\n<p>ACCETTAZIONE E RINUNCIA DEI COOKIE<br \/>\nProseguendo nella navigazione su questo sito, chiudendo la fascetta informativa o facendo click in una qualsiasi parte della pagina o scorrendola per evidenziare ulteriore contenuto, si accetta la Cookie Policy e verranno impostati e raccolti i cookie. In caso di mancata accettazione dei cookie mediante abbandono della navigazione, eventuali cookie gi\u00e0 registrati localmente nel Suo browser rimarranno ivi registrati ma non saranno pi\u00f9 letti n\u00e9 utilizzati da noi fino ad una successiva ed eventuale accettazione della Policy. Lei avr\u00e0 sempre la possibilit\u00e0 di rimuovere tali cookie in qualsiasi momento attraverso le modalit\u00e0 citate.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRIVACY Privacy Policy \u2013 Informativa in materia di protezione dei dati personali (13 del GDPR 2016\/679) In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano. Si tratta di una informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del GDPR 2016\/679 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy policy - Letizia Innocenti - pianista<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"zh_TW\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy policy - Letizia Innocenti - pianista\" \/>\n<meta property=\"og:description\" content=\"PRIVACY Privacy Policy \u2013 Informativa in materia di protezione dei dati personali (13 del GDPR 2016\/679) In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano. Si tratta di una informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del GDPR 2016\/679 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Letizia Innocenti - pianista\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/letiziainnocenti.it\/it\/#website\",\"url\":\"https:\/\/letiziainnocenti.it\/it\/\",\"name\":\"Letizia Innocenti - pianista\",\"description\":\"Pianista - Docente - Musicologa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/letiziainnocenti.it\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-TW\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#webpage\",\"url\":\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/\",\"name\":\"Privacy policy - Letizia Innocenti - pianista\",\"isPartOf\":{\"@id\":\"https:\/\/letiziainnocenti.it\/it\/#website\"},\"datePublished\":\"2016-10-17T13:18:11+00:00\",\"dateModified\":\"2016-10-17T13:18:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"zh-TW\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/letiziainnocenti.it\/zh-hant\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy policy\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy policy - Letizia Innocenti - pianista","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/","og_locale":"zh_TW","og_type":"article","og_title":"Privacy policy - Letizia Innocenti - pianista","og_description":"PRIVACY Privacy Policy \u2013 Informativa in materia di protezione dei dati personali (13 del GDPR 2016\/679) In questa pagina si descrivono le modalit\u00e0 di gestione del sito in riferimento al trattamento dei dati personali degli utenti che lo consultano. Si tratta di una informativa che \u00e8 resa anche ai sensi dell\u2019art. 13 del GDPR 2016\/679 &hellip;","og_url":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/","og_site_name":"Letizia Innocenti - pianista","twitter_card":"summary","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/letiziainnocenti.it\/it\/#website","url":"https:\/\/letiziainnocenti.it\/it\/","name":"Letizia Innocenti - pianista","description":"Pianista - Docente - Musicologa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/letiziainnocenti.it\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-TW"},{"@type":"WebPage","@id":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#webpage","url":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/","name":"Privacy policy - Letizia Innocenti - pianista","isPartOf":{"@id":"https:\/\/letiziainnocenti.it\/it\/#website"},"datePublished":"2016-10-17T13:18:11+00:00","dateModified":"2016-10-17T13:18:11+00:00","breadcrumb":{"@id":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#breadcrumb"},"inLanguage":"zh-TW","potentialAction":[{"@type":"ReadAction","target":["https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/letiziainnocenti.it\/zh-hant\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/letiziainnocenti.it\/zh-hant\/"},{"@type":"ListItem","position":2,"name":"Privacy policy"}]}]}},"_links":{"self":[{"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/pages\/768\/"}],"collection":[{"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/comments\/?post=768"}],"version-history":[{"count":0,"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/pages\/768\/revisions\/"}],"wp:attachment":[{"href":"https:\/\/letiziainnocenti.it\/zh-hant\/wp-json\/wp\/v2\/media\/?parent=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}